{"id":6801,"date":"2019-05-01T06:00:00","date_gmt":"2019-05-01T06:00:00","guid":{"rendered":"https:\/\/lrnatestbed.org\/the-wall-will-fall-the-american-people-dont-separate-families\/"},"modified":"2023-05-17T22:55:51","modified_gmt":"2023-05-17T22:55:51","slug":"el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias","status":"publish","type":"post","link":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/","title":{"rendered":"El muro se derribar\u00e1\u2004\u2013 El pueblo norteamericano no separa familias"},"content":{"rendered":"<div id=\"main-left-side\">\n<section id=\"article-outer-container\">\n<div id=\"post-3581\" class=\"post-3581 post type-post status-publish format-standard hentry category-article category-capitalism category-corporate-state category-immigrant-rights category-movements category-new-technology category-poverty category-robotics-electronic-technology category-spanish category-vol-29-ed-3-may-june-2019\">\n<section id=\"article-container\">La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta lo siguiente:<\/p>\n<p>\u201cDe ni\u00f1a no me permit\u00edan quedarme en casa de amistades. Yo odiaba que todas mis amigas lo hac\u00edan, pero a m\u00ed no me dejaban. Ahora comprendo que mis padres indocumentados nunca se sent\u00edan seguros y evitaban cualquier situaci\u00f3n en que podr\u00edamos encontrarnos con agentes de la ley de cualquier tipo. Recientemente estuve en Tijuana participando en actividades humanitarias de miles de trabajadores norteamericanos que traen mantas, pa\u00f1ales, f\u00f3rmula infantil y art\u00edculos de aseo para los refugiados de Centroam\u00e9rica. Habl\u00e9 con Tania, de 22 a\u00f1os de edad, quien dej\u00f3 a sus dos criaturas en su Honduras natal por temor de no poder protegerlas durante la arriesgada jornada. Lloraba al contar que sali\u00f3 de la casa a las dos de la ma\u00f1ana sin despedirse. Sandra tambi\u00e9n ten\u00eda miedo de lo que le pasar\u00eda a sus hijos si los dejaba. Ella se los llev\u00f3 y los vio llorar y sufrir de tanto caminar y tan poco comer. Ahora que han sobrevivido el penoso viaje temen que los agentes de Inmigraci\u00f3n y Aduanas (ICE) les quiten sus hijos.\u201d<\/p>\n<h4><strong>El Terror en la Frontera\u00a0<\/strong><\/h4>\n<p>La mayor\u00eda de los norteamericanos no pueden imaginar el terror y el trauma de padres a quienes ICE les arrebata los hijos\u2014o cualquier agencia gubernamental que separa (o atacan con gases lacrim\u00f3genos) a familias hambrientas y desesperadas. Un reciente memor\u00e1ndum y una auditor\u00eda federal confirman que la administraci\u00f3n de Trump separ\u00f3 a miles de ni\u00f1os m\u00e1s de lo que se sab\u00eda anteriormente. La administraci\u00f3n de Trump y el entonces Fiscal General, Jeff Sessions, implementaron una pol\u00edtica de terror contra los refugiados para impedir su entrada en EE.UU. Las separaciones empezaron en 2017 pero no fueron oficialmente anunciadas hasta mayo de 2018 por Sessions, en el marco de la pol\u00edtica de \u201czero tolerancia\u201d de la administraci\u00f3n.<\/p>\n<p>A mediados de diciembre de 2018, la poblaci\u00f3n de ni\u00f1os migrantes se aproximaba a 15,000 ni\u00f1os, y la Oficina de Reasentamiento de Refugiados (ORR, por sus siglas en ingl\u00e9s) se quedaba sin suficientes camas en su red de 130 refugios. Cuando el refugio m\u00e1s grande, el campamento de tiendas en el desierto de Tornillo, Texas, se neg\u00f3 a renovar su contrato, ORR hizo un repentino cambio en su pol\u00edtica que simplificaba c\u00f3mo se investigaban a los patrocinadores de refugiados. Seg\u00fan un informe de National Public Radio, un correo electr\u00f3nico del Departamento de Salud y Servicios Humanos (HHS) declar\u00f3 que, desde el 20 de enero de 2019, el n\u00famero de ni\u00f1os bajo su custodia hab\u00eda disminuido a 10,700 por su entrega a patrocinadores, una reducci\u00f3n de la cifra m\u00e1xima de 14,600 el mes anterior. El Southern Poverty Law Center (organizaci\u00f3n de defensor\u00eda legal) inform\u00f3 que el componente de ORR del arreglo de HHS con ICE, utiliza a \u201clos ni\u00f1os como cebo para atrapar a los patrocinadores y llevarlos a audiencias de deportaci\u00f3n. Sabemos esto porque lo han hecho por escrito y declaran que lo est\u00e1n haciendo.\u201d<\/p>\n<p>Numerosas demandas acusan al gobierno de utilizar la reclusi\u00f3n de los ni\u00f1os como modo de castigar y deportar a ni\u00f1os y familiares. Cuando se presentan miembros de la familia para acoger a un ni\u00f1o migrante en su hogar, los agentes de ICE arrestan al patrocinador si est\u00e1 en el pa\u00eds sin documentaci\u00f3n. Seg\u00fan los abogados involucrados, en el \u00faltimo a\u00f1o se han arrestado a 170 patrocinadores y se han puesto en procesos de deportaci\u00f3n. Usaron los ni\u00f1os como carnada para atrapar a la gente dispuesta a patrocinarlos, justamente sabiendo que esto significar\u00eda detenciones m\u00e1s largas para los ni\u00f1os.<\/p>\n<p>Ahora nos acabamos de enterar de que nunca se dignaron a montar un sistema de seguimiento, as\u00ed que, a pesar de que las cortes le ordenaron a la administraci\u00f3n a reunir las familias, no saben d\u00f3nde se encuentran los ni\u00f1os. Est\u00e1n \u201cperdidos\u201d en el sistema.<\/p>\n<h4><strong>La Globalizaci\u00f3n Separa a Las Familias<\/strong><\/h4>\n<p>La pol\u00edtica de separar a familias forma parte de la estrategia de la clase gobernante para bregar con el creciente n\u00famero de gente desesperada y hambrienta en ambos lados de la frontera. Hoy enfrentamos una clase capitalista globalizada que tiene f\u00e1bricas con m\u00e1s robots y menos personas, expulsando de la producci\u00f3n a millones de trabajadores por toda la tierra y lanz\u00e1ndolos a la creciente clase de gente permanentemente sin trabajo y empobrecida.<\/p>\n<p>En EE.UU., la pobreza conduce a la c\u00e1rcel. De hecho, cuando le preguntaron sobre la pol\u00edtica de fronteras a Kirsten Nielsen, Secretaria de Seguridad Nacional, contesto esto: \u201cLo hacemos todos los d\u00edas en todas partes del pa\u00eds\u201d. De acuerdo al New York Times, se calcula que hay un cuarto de mill\u00f3n de ni\u00f1os norteamericanos con una madre soltera en la c\u00e1rcel, muchas en espera de una audiencia, acusadas de delitos menores.<\/p>\n<p>Una parte de la estrategia de la clase gobernante es atacar y levantar muros para dividirnos. Ellos atacan y culpan a los migrantes para ocultar la verdad de que est\u00e1n abandonado a todos los trabajadores. Los estudios hechos hallan que en promedio una familia necesita un ingreso del doble del nivel federal de pobreza para afrontar los gastos b\u00e1sicos. Por eso hay 400,000 ni\u00f1os en el sistema de cuidado de crianza, muchos de ellos tambi\u00e9n arrancados de los brazos de sus padres. El profesor de sociolog\u00eda, Christopher Wileman, de la Universidad de Cornell, explica que a menudo se colocan a ni\u00f1os en cuidado de acogida por sufrir supuesto \u201cabuso\u201d, pero no hay tal abuso. Es m\u00e1s una suerte de \u201cnegligencia\u201crelacionada con la pobreza. Por ejemplo, cuando las familias no pueden pagar por el agua y se les corta el agua, un departamento de servicios sociales se lleva a los ni\u00f1os.<\/p>\n<p>Podr\u00eda parecer que estos ataques a familias en ambos lados de la frontera no est\u00e1n relacionados, pero no es as\u00ed. Cada ataque de la clase dominante es un intento de dividir y aislarnos. Por eso est\u00e1n infundiendo temores de desempleo y terrorismo a los trabajadores de EE.UU., que se vuelven m\u00e1s y m\u00e1s desesperados por el hambre.<\/p>\n<p>Como se explic\u00f3 mediante la reciente visita a la Caravana en Tijuana, \u201cEsto es todo lo opuesto a la \u00e9poca de mi padre. \u00c9l pudo tomar clases de soldadura gratuitas en una universidad comunitaria y conseguir un trabajo soldando en un astillero que operaba casi las 24 horas al d\u00eda, empleando a miles de trabajadores en tres turnos. Con un solo salario, mis padres pudieron comprar una casita en Compton, California, y tomar peque\u00f1as vacaciones. Les costaba unos $75 por trimestre mandar a su hija a la Universidad de California, en Los \u00c1ngeles (UCLA). Hoy d\u00eda, la mayor\u00eda de los trabajadores en este pa\u00eds ya no pueden hacerlo\u201d.<\/p>\n<p>Es por eso que est\u00e1n enga\u00f1ando con temores y odio a gente que padece hambre y est\u00e1 cada vez m\u00e1s desesperada. Estas violentas embestidas contra los migrantes y violencia contra trabajadores norteamericanos est\u00e1n todas vinculadas. La clase dirigente no tiene soluciones serias para trabajadores que no necesitan. Ah\u00ed est\u00e1 su punto d\u00e9bil. No tienen de otra que no sea seguir con sus ataques para mantener el control en una nueva era en que el proceso de producci\u00f3n excluye cada vez a m\u00e1s trabajadores.<\/p>\n<p>\u00bfEst\u00e1 funcionando? Una reciente encuesta Gallup revel\u00f3 que el 61% de la poblaci\u00f3n norteamericana est\u00e1 en contra de la deportaci\u00f3n de toda la gente indocumentada en el pa\u00eds, el 60% se opone al muro fronterizo y el 81% quiere una v\u00eda a la ciudadan\u00eda para los inmigrantes sin tarjeta verde.<\/p>\n<h4><strong>La Necesidad de la Unidad de Clase<\/strong><\/h4>\n<p>Hoy, la unidad de la clase trabajadora es m\u00e1s que un mero sue\u00f1o o una exigencia. Es la \u00fanica manera de realmente asegurar la supervivencia de millones de personas. El capitalismo de alta tecnolog\u00eda ha engendrado una clase gobernante a nivel mundial, incluyendo a billonarios como Carlos Slim Hel\u00fa de M\u00e9xico, la cuarta m\u00e1s rica persona del planeta. Al emplear la rob\u00f3tica para rendir innecesarios a los trabajadores, aumentan la ya terrible pobreza que azota a los pa\u00edses m\u00e1s pobres, y al mismo tiempo dan lugar a una igualdad de pobreza entre los millones de trabajadores de los pa\u00edses m\u00e1s ricos. En los EE.UU., millones de trabajadores han perdido la calidad de vida que una vez gozaron como soborno social por apoyar las guerras y desigualdades del sistema. Trabajadores de todos los colores y nacionalidades ahora forman parte de la clase trabajadora, cuyas condiciones de vida forman el fundamento material para comprender que constituyen, objetivamente, una clase comunista, cuyas necesidades no pueden ser satisfechas bajo el capitalismo.<\/p>\n<p>El comprender que nuestras condiciones de vida est\u00e1n vinculadas a nuestra nueva ubicaci\u00f3n en la sociedad como trabajadores \u201cinnecesarios\u201d es el primer paso para poder empezar a mejorar nuestra situaci\u00f3n. El primer paso siempre es el m\u00e1s dif\u00edcil, pero una vez lo tomamos se ve claramente que los \u201cinnecesarios\u201d son las corporaciones.<\/p>\n<p>Podemos ponerle fin al sufrimiento de nuestras comunidades cogiendo el control de las corporaciones que manejan a ambos partidos pol\u00edticos. Podemos usar nuevas tecnolog\u00edas, tan incre\u00edblemente productivas, para servir a nuestra salud, nuestra educaci\u00f3n y nuestras diversiones, de paso acabando con las guerras y salvando nuestro planeta. Empieza t\u00fa mismo ahora compartiendo y discutiendo este art\u00edculo. \u00a1\u00danete a la Liga de Revolucionarios por una Nueva Am\u00e9rica! \u00a1Ac\u00e9rcate a nosotros! Merecemos un mundo mejor.<\/p>\n<p><strong>mayo\/junio 2019. vol.29. Ed3<br \/>\n<\/strong>Este art\u00edculo origin\u00f3 en Rally, camaradas!<br \/>\nCORREO:\u00a0\u00a0<u>Box 477113 Chicago, IL 60647<\/u>\u00a0<u>rally@lrna.org<\/u><br \/>\nSe pueden reproducir art\u00edculos a menos de que se indique lo contrario.<br \/>\nPor favor incluya este mensaje con cualquier reproducci\u00f3n.<\/p>\n<\/section>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[196,200,226,211,202,204],"tags":[],"class_list":["post-6801","post","type-post","status-publish","format-standard","category-articulo","category-capitalismo","category-derechos-de-los-inmigrantes","category-inmigracion-migracion","category-pobreza_capitalist_class_system","category-tecnologia-produccion-sin-mano-de-obra"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Web Designer - Mauricio\"\/>\n\t<meta name=\"google-site-verification\" content=\"1XxvXmRwhGwQ0tsTTsKXy5R4fvTuv8OVEYVOEuqEAyA\" \/>\n\t<meta name=\"keywords\" content=\"art\u00edculo,capitalismo,derechos de los inmigrantes,inmigraci\u00f3n \/ migraci\u00f3n,pobreza,tecnolog\u00eda \/ producci\u00f3n sin mano de obra\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica - Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica\" \/>\n\t\t<meta property=\"og:description\" content=\"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-01T06:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-17T22:55:51+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#blogposting\",\"name\":\"El muro se derribar\\u00e1 \\u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"headline\":\"El muro se derribar\\u00e1\\u2004\\u2013 El pueblo norteamericano no separa familias\",\"author\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/web-designer-mauricio\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\"},\"datePublished\":\"2019-05-01T06:00:00-04:00\",\"dateModified\":\"2023-05-17T22:55:51-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#webpage\"},\"articleSection\":\"Art\\u00edculo, Capitalismo, Derechos de los inmigrantes, Inmigraci\\u00f3n \\\/ Migraci\\u00f3n, Pobreza, Tecnolog\\u00eda \\\/ Producci\\u00f3n sin mano de obra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"name\":\"Sistema de clase capitalista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"position\":2,\"name\":\"Sistema de clase capitalista\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/#listItem\",\"name\":\"Capitalismo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/#listItem\",\"position\":3,\"name\":\"Capitalismo\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#listItem\",\"name\":\"El muro se derribar\\u00e1\\u2004\\u2013 El pueblo norteamericano no separa familias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"name\":\"Sistema de clase capitalista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#listItem\",\"position\":4,\"name\":\"El muro se derribar\\u00e1\\u2004\\u2013 El pueblo norteamericano no separa familias\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/#listItem\",\"name\":\"Capitalismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\",\"name\":\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"description\":\"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\\u00f3n de cambio revolucionario\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"telephone\":\"+12699031659\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/web-designer-mauricio\\\/#author\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/web-designer-mauricio\\\/\",\"name\":\"Web Designer - Mauricio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f031e660b7c75313661327b537b6d0eddeb62fd2a1b9e0d7be77320844fb8169?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Web Designer - Mauricio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#webpage\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/\",\"name\":\"El muro se derribar\\u00e1 \\u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"description\":\"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\\u00f3 a Tijuana, M\\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/web-designer-mauricio\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/web-designer-mauricio\\\/#author\"},\"datePublished\":\"2019-05-01T06:00:00-04:00\",\"dateModified\":\"2023-05-17T22:55:51-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"name\":\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"alternateName\":\"Rally!\",\"description\":\"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\\u00f3n de cambio revolucionario\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica<\/title>\n\n","aioseo_head_json":{"title":"El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta","canonical_url":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/","robots":"max-image-preview:large","keywords":"art\u00edculo,capitalismo,derechos de los inmigrantes,inmigraci\u00f3n \/ migraci\u00f3n,pobreza,tecnolog\u00eda \/ producci\u00f3n sin mano de obra","webmasterTools":{"google-site-verification":"1XxvXmRwhGwQ0tsTTsKXy5R4fvTuv8OVEYVOEuqEAyA","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#blogposting","name":"El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","headline":"El muro se derribar\u00e1\u2004\u2013 El pueblo norteamericano no separa familias","author":{"@id":"https:\/\/rally-theleague.org\/es\/author\/web-designer-mauricio\/#author"},"publisher":{"@id":"https:\/\/rally-theleague.org\/es\/#organization"},"datePublished":"2019-05-01T06:00:00-04:00","dateModified":"2023-05-17T22:55:51-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#webpage"},"isPartOf":{"@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#webpage"},"articleSection":"Art\u00edculo, Capitalismo, Derechos de los inmigrantes, Inmigraci\u00f3n \/ Migraci\u00f3n, Pobreza, Tecnolog\u00eda \/ Producci\u00f3n sin mano de obra"},{"@type":"BreadcrumbList","@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/rally-theleague.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","name":"Sistema de clase capitalista"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","position":2,"name":"Sistema de clase capitalista","item":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/#listItem","name":"Capitalismo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/#listItem","position":3,"name":"Capitalismo","item":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#listItem","name":"El muro se derribar\u00e1\u2004\u2013 El pueblo norteamericano no separa familias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","name":"Sistema de clase capitalista"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#listItem","position":4,"name":"El muro se derribar\u00e1\u2004\u2013 El pueblo norteamericano no separa familias","previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/#listItem","name":"Capitalismo"}}]},{"@type":"Organization","@id":"https:\/\/rally-theleague.org\/es\/#organization","name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","url":"https:\/\/rally-theleague.org\/es\/","telephone":"+12699031659"},{"@type":"Person","@id":"https:\/\/rally-theleague.org\/es\/author\/web-designer-mauricio\/#author","url":"https:\/\/rally-theleague.org\/es\/author\/web-designer-mauricio\/","name":"Web Designer - Mauricio","image":{"@type":"ImageObject","@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f031e660b7c75313661327b537b6d0eddeb62fd2a1b9e0d7be77320844fb8169?s=96&d=mm&r=g","width":96,"height":96,"caption":"Web Designer - Mauricio"}},{"@type":"WebPage","@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#webpage","url":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/","name":"El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/rally-theleague.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/#breadcrumblist"},"author":{"@id":"https:\/\/rally-theleague.org\/es\/author\/web-designer-mauricio\/#author"},"creator":{"@id":"https:\/\/rally-theleague.org\/es\/author\/web-designer-mauricio\/#author"},"datePublished":"2019-05-01T06:00:00-04:00","dateModified":"2023-05-17T22:55:51-04:00"},{"@type":"WebSite","@id":"https:\/\/rally-theleague.org\/es\/#website","url":"https:\/\/rally-theleague.org\/es\/","name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","alternateName":"Rally!","description":"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","inLanguage":"es-ES","publisher":{"@id":"https:\/\/rally-theleague.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica - Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","og:type":"article","og:title":"El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","og:description":"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta","og:url":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/","article:published_time":"2019-05-01T06:00:00+00:00","article:modified_time":"2023-05-17T22:55:51+00:00","twitter:card":"summary_large_image","twitter:title":"El muro se derribar\u00e1 \u2013 El pueblo norteamericano no separa familias - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","twitter:description":"La lucha por unir al pueblo norteamericano en contra de los ataques del gobierno hacia de los inmigrantes y la separaci\u00f3n de familias se intensifica. Hace poco una revolucionaria que participa en ese movimiento nacional viaj\u00f3 a Tijuana, M\u00e9xico, para hablar con miembros de la Caravana de Inmigrantes, que acababan de llegar de Honduras. Cuenta"},"aioseo_meta_data":{"post_id":"6801","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 22:03:08","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2025-01-20 04:55:32","updated":"2026-05-13 22:03:08","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/\" title=\"Sistema de clase capitalista\">Sistema de clase capitalista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/\" title=\"Capitalismo\">Capitalismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl muro se derribar\u00e1\u2004\u2013 El pueblo norteamericano no separa familias\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/rally-theleague.org\/es\/"},{"label":"Sistema de clase capitalista","link":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/"},{"label":"Capitalismo","link":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/"},{"label":"El muro se derribar\u00e1\u2004\u2013 El pueblo norteamericano no separa familias","link":"https:\/\/rally-theleague.org\/es\/el-muro-se-derribara-el-pueblo-norteamericano-no-separa-familias\/"}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/6801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/comments?post=6801"}],"version-history":[{"count":1,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/6801\/revisions"}],"predecessor-version":[{"id":6802,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/6801\/revisions\/6802"}],"wp:attachment":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/media?parent=6801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/categories?post=6801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/tags?post=6801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}