{"id":8538,"date":"2025-08-27T19:58:32","date_gmt":"2025-08-27T23:58:32","guid":{"rendered":"https:\/\/rally-theleague.org\/?p=8538"},"modified":"2025-08-28T09:49:14","modified_gmt":"2025-08-28T13:49:14","slug":"el-ataque-contra-los-inmigrantes-y-todos-nosotros","status":"publish","type":"post","link":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/","title":{"rendered":"El Ataque Contra Los Inmigrantes y Todos Nosotros\u00a0"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Demonstration Against ICE Raid in Monrovia CA\" src=\"\/\/www.youtube.com\/embed\/wMMbL858Qxo\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">El ataque generalizado contra los inmigrantes que se est\u00e1 desarrollando ante nosotros en Los \u00c1ngeles y muchos otros lugares es solo la punta de lanza de la ofensiva contra toda la clase trabajadora estadounidense. Busca desarmarnos al parecer dirigido \u00fanicamente contra los inmigrantes, cuando la intenci\u00f3n es crear una fuerza policial masiva que pueda dirigirse contra cualquiera que se interponga en el camino de Trump y los multimillonarios corporativos que lo respaldan. Lo que el presidente Trump, el subjefe de gabinete para pol\u00edticas, Stephen Miller, la jefa de Seguridad Nacional, Kristi Noem, y el director de ICE, Thomas Homan, dicen y hacen se basa en la mentira de que los inmigrantes, asilados, refugiados y minor\u00edas son los culpables del deterioro del nivel de vida de los estadounidenses comunes.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Con la mentira de que Trump y sus secuaces solo persiguen a los criminales \u2014&#8221;lo peor de lo peor&#8221;\u2014, la maquinaria de deportaci\u00f3n masiva que Trump prometi\u00f3 a su base en las elecciones presidenciales de 2024 est\u00e1 cobrando impulso. El 7 de junio de 2025, Trump orden\u00f3 el despliegue ilegal de 5000 tropas federales, incluyendo la Guardia Nacional, otros oficiales federales y 700 infantes de marina estadounidenses, en Los \u00c1ngeles. Esta acci\u00f3n constituye una clara violaci\u00f3n de la ley <a href=\"https:\/\/www.brennancenter.org\/our-work\/research-reports\/posse-comitatus-act-explained\"><span class=\"s1\">Posse Comitatus<\/span><\/a>.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Fue ordenada supuestamente para proteger la propiedad del gobierno y a los <a href=\"https:\/\/www.cbsnews.com\/news\/trump-title-10-national-guard-deployment-los-angeles-authority-meaining\/?form=MG0AV3\"><span class=\"s1\">agentes del ICE<\/span><\/a>, quienes estaban siendo cuestionados por j\u00f3venes y otros residentes de la comunidad por arrestar a personas presuntamente indocumentadas en tribunales, calles y otros lugares p\u00fablicos. Todo esto ocurri\u00f3 sin el consentimiento y a pesar de las protestas del gobernador de California, Gavin Newsom, y la alcaldesa de Los \u00c1ngeles, Karen Bass.<\/span><\/p>\n<p class=\"p2\"><span style=\"font-size: 18pt;\">Esta mentira de criminalidad, que fuentes acreditadas cuestionan, ha desatado:<\/span><\/p>\n<p class=\"p3\"><span style=\"font-size: 18pt;\">\u2022 La devastaci\u00f3n econ\u00f3mica, f\u00edsica y emocional que sufri\u00f3 Los \u00c1ngeles,<\/span><\/p>\n<p class=\"p4\"><span style=\"font-size: 18pt;\"><span class=\"s2\">\u2022 La <\/span>extralimitaci\u00f3n de la autoridad estatal y municipal,<\/span><\/p>\n<p class=\"p3\"><span style=\"font-size: 18pt;\">\u2022 Violaciones flagrantes de los derechos humanos, reportadas en las noticias nacionales y en las redes sociales.<\/span><\/p>\n<p class=\"p3\"><span style=\"font-size: 18pt;\">\u2022 Stephen Miller anunci\u00f3 objetivos de deportar a\u00fan m\u00e1s inmigrantes, aumentando sus cuotas diarias de 1.000 a 3.000, a pesar de los relatos de que incluso ciudadanos estadounidenses fueron arrestados y acosados.<\/span><\/p>\n<p class=\"p6\"><span style=\"font-size: 18pt;\">Para financiar deportaciones masivas, Trump forz\u00f3 la aprobaci\u00f3n de la &#8220;<a href=\"https:\/\/federalnewsnetwork.com\/budget\/2025\/07\/dhs-prepares-for-unprecedented-spending-surge-under-big-beautiful-bill\/?form=MG0AV3\"><span class=\"s1\">Gran y Hermosa Ley<\/span><\/a>&#8221; (HR 1) a pesar incluso de la oposici\u00f3n republicana. Esta ley otorga 1.4 billones de d\u00f3lares al ICE y al Departamento de Seguridad Nacional. La asignaci\u00f3n de 75 mil millones de d\u00f3lares al ICE lo convierte en uno de los organismos de seguridad con mayor financiaci\u00f3n federal del pa\u00eds. Su financiaci\u00f3n supera la financiaci\u00f3n militar de muchos pa\u00edses del <a href=\"https:\/\/www.independent.co.uk\/news\/world\/americas\/us-politics\/ice-funding-world-militaries-b2790466.html?form=MG0AV3\"><span class=\"s1\">mundo<\/span><\/a>.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Las mentiras antiinmigrantes de Trump ayudan a encubrir que est\u00e1 atacando a todos los trabajadores, ya que la HR 1 tambi\u00e9n recorta dr\u00e1sticamente la financiaci\u00f3n federal del SNAP en 186.7 mil millones de d\u00f3lares durante la <a href=\"https:\/\/alliancetoendhunger.org\/wp-content\/uploads\/2025\/07\/2025.07.31-Impacts-of-H.R.1-Final.pdf?form=MG0AV3\"><span class=\"s1\">pr\u00f3xima d\u00e9cada<\/span><\/a>, lo que eliminar\u00e1 los programas de alimentaci\u00f3n para muchos adultos mayores y ni\u00f1os. Se espera que hasta 15 millones de estadounidenses pierdan la cobertura de <a href=\"https:\/\/www.cbpp.org\/research\/health\/medicaid-work-requirements-will-take-away-coverage-from-millions-state-and\"><span class=\"s1\">Medicaid para 2034<\/span><\/a>.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Tambi\u00e9n, los adultos mayores se ver\u00e1n afectados negativamente por los recortes a Medicare y la seguridad social. A pesar de las promesas y mentiras de Trump, la aprobaci\u00f3n de la HR 1 se produjo a expensas del sustento de los estadounidenses, tanto los nacidos en Estados Unidos como los indocumentados.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Los estadounidenses observan con nerviosismo la crueldad y el terror desatados por oficiales armados, enmascarados y cazarrecompensas que no se identifican. Las <a href=\"https:\/\/www.yahoo.com\/news\/articles\/americans-support-trump-deportation-plan-140158661.html?form=MG0AV3\"><span class=\"s1\">encuestas<\/span><\/a> comienzan a mostrar que los estadounidenses ya no apoyan las pol\u00edticas antiinmigrantes de Trump, posiblemente porque comienzan a comprender que nos persigue a todos. Su manipulaci\u00f3n electoral mediante la manipulaci\u00f3n de distritos electorales y su intento de derogar la ciudadan\u00eda por nacimiento es absolutamente aterradora para quienes creen en la democracia y la Constituci\u00f3n.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">La cuesti\u00f3n del inmigrante indocumentado hoy en d\u00eda debe verse en el contexto de la globalizaci\u00f3n y el capitalismo en la era de la producci\u00f3n con electr\u00f3nica digital. Desde aproximadamente la d\u00e9cada de 1970, se ha permitido a las corporaciones automatizar la producci\u00f3n y explorar el mundo en busca de mano de obra barata en pa\u00edses con escasas protecciones ambientales y laborales para maximizar sus ganancias. Esto ha perjudicado a todos los trabajadores al generar desempleo, reducir los salarios y obligar a las personas a migrar en busca de trabajo y una vida mejor para sus familias. De hecho, hoy en d\u00eda una de cada tres personas en el mundo son trabajadores migrantes.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Los trabajadores, incluidos los indocumentados, no pueden vivir sin trabajo, y los capitalistas no pueden generar empleos en una econom\u00eda basada en la producci\u00f3n digital, que est\u00e1 eliminando empleos sistem\u00e1ticamente. La clase dominante, sin soluciones reales, recurre a la b\u00fasqueda de chivos expiatorios y a t\u00e1cticas de &#8220;divide y vencer\u00e1s&#8221; para controlar no solo al trabajador inmigrante, sino a toda la clase. Su objetivo es criminalizar a un sector de la clase trabajadora y enfrentarnos entre nosotros para que no podamos unirnos contra un gobierno controlado por las corporaciones tecnol\u00f3gicas.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><b>\u00bfCu\u00e1l es la respuesta a los ataques?<\/b> Es, acciones unidas.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Esto se est\u00e1 desarrollando en dos niveles. En primer lugar, la ayuda mutua, la autodefensa, las redes de respuesta r\u00e1pida y otras formas de organizaci\u00f3n comunitaria se est\u00e1n llevando a cabo en Los \u00c1ngeles y en muchos otros lugares.<\/span><\/p>\n<p class=\"p9\"><span style=\"font-size: 18pt;\">En segundo lugar, las protestas p\u00fablicas, marchas, tomas de poder, etc. est\u00e1n obligando a los funcionarios estatales y locales de California a adoptar una postura p\u00fablica, en contra de que Trump y Hegseth se extralimiten en su gobernador, y a unirse al llamado para que las fuerzas militarizadas sean retiradas de Los \u00c1ngeles. Hasta el LAPD se vi\u00f3 en la posici\u00f3n de tener que defender el derecho democr\u00e1tico a protestar, aunque muchos del p\u00fablico todav\u00eda lo temen.<\/span><\/p>\n<figure id=\"attachment_8523\" aria-describedby=\"caption-attachment-8523\" style=\"width: 293px\" class=\"wp-caption alignright\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\" wp-image-8523\" src=\"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/08\/Defend-imigrant-families-banner-8.15.25.jpg?resize=293%2C204&#038;ssl=1\" alt=\"\" width=\"293\" height=\"204\" srcset=\"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/08\/Defend-imigrant-families-banner-8.15.25.jpg?resize=300%2C208&amp;ssl=1 300w, https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/08\/Defend-imigrant-families-banner-8.15.25.jpg?resize=150%2C104&amp;ssl=1 150w, https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/08\/Defend-imigrant-families-banner-8.15.25.jpg?w=320&amp;ssl=1 320w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><figcaption id=\"caption-attachment-8523\" class=\"wp-caption-text\"><span style=\"font-size: 8pt;\">Monrovia, CA, August 15, 2025 &#8211; March and vigil protesting the death of Carlos Roberto Montoya during an ICE raid at a local Home Depot the day before.<\/span><br \/><span style=\"font-size: 8pt;\">Credit: classsnrace<\/span><\/figcaption><\/figure>\n<p class=\"p9\"><span style=\"font-size: 18pt;\">Mientras tanto, se deben cumplir las leyes estatales a pesar de que ICE act\u00faa en nombre del gobierno federal. La SB 54 de California es una ley de 2017 que impide que las agencias policiales estatales y locales utilicen recursos en nombre de las agencias federales de inmigraci\u00f3n. Se ha propuesto y deber\u00eda exigirse un servicio de defensa jur\u00eddica patrocinado por el Estado. Se necesitan medidas que exijan la identificaci\u00f3n de los agentes federales de ICE mediante uniformes e insignias, y proh\u00edban su presencia sin m\u00e1scara.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Las redadas de ICE y los ataques a inmigrantes aumentan el costo de vida para todos. Cuando los trabajadores agr\u00edcolas no pueden cosechar, los precios de los alimentos suben. Los costos de construcci\u00f3n aumentan a medida que los trabajadores se quedan en casa.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Las industrias de servicios, como los hogares de ancianos, enfrentan escasez de mano de obra al finalizar las protecciones del <a href=\"https:\/\/www.uscis.gov\/humanitarian\/temporary-protected-status\"><span class=\"s1\">TPS<\/span><\/a> para los haitianos y otros inmigrantes en trabajos esenciales. Esta escasez de mano de obra aumenta los precios, reduce los empleos directa e indirectamente y adem\u00e1s perjudica a las peque\u00f1as empresas.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Las acciones de Trump revelan a qui\u00e9n sirve realmente el gobierno. &#8220;Make America Great Again&#8221; fue una cortina de humo para transferir riqueza hacia arriba mientras constru\u00eda un estado policial, perjudicando a millones, incluidos los votantes de MAGA. Esta administraci\u00f3n solo les ofrece a los trabajadores guerra, divisi\u00f3n y destrucci\u00f3n. Trump y sus compinches no son aptos para gobernar. Debemos unirnos como clase trabajadora independiente de los ricos realizando esta necesidad, antes de que sea demasiado tarde.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><b>Publicado el\u00a0A<\/b><span class=\"s1\"><b>gosto 27<\/b><\/span><b> <\/b><b>de 2025<\/b><\/span><br \/>\n<span style=\"font-size: 18pt;\">Este art\u00edculo se origin\u00f3 en \u00a1Agrup\u00e9monos!<\/span><br \/>\n<span style=\"font-size: 18pt;\">CORREOS. Box 408002 Chicago, IL 60640<\/span><br \/>\n<span style=\"font-size: 18pt;\">rally@lrna.org<\/span><br \/>\n<span style=\"font-size: 18pt;\">Libre de reproducir a menos que se indique lo contrario. Incluya este mensaje con cualquier reproducci\u00f3n.<\/span><\/p>\n<p><strong><span style=\"font-size: 24pt;\">Lea sobre la lucha contra ICE y el fascismo<\/span><\/strong><\/p>\n<p><strong><span style=\"font-size: 18pt;\"><a href=\"https:\/\/rally-theleague.org\/es\/category\/politica-fascismo\/el-fascismo-hoy\/\">https:\/\/rally-theleague.org\/es\/category\/politica-fascismo\/el-fascismo-hoy\/<\/a><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.<\/p>\n","protected":false},"author":11,"featured_media":8523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[196,339,200,218,217,259,211,227,357,204],"tags":[],"class_list":["post-8538","post","type-post","status-publish","format-standard","has-post-thumbnail","category-articulo-destacado-espanol","category-capitalismo","category-el-fascismo-hoy","category-elecciones-gobernanza","category-featured-es","category-inmigracion-migracion","category-pobreza_race-class_gender","category-spotlight-english-es","category-tecnologia-produccion-sin-mano-de-obra"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Brandon TekNoid\"\/>\n\t<meta name=\"google-site-verification\" content=\"1XxvXmRwhGwQ0tsTTsKXy5R4fvTuv8OVEYVOEuqEAyA\" \/>\n\t<meta name=\"keywords\" content=\"art\u00edculo,art\u00edculo destacado - espa\u00f1ol,capitalismo,el fascismo hoy,elecciones \/ gobernanza,featured,inmigraci\u00f3n \/ migraci\u00f3n,pobreza,spotlight &#8211; english,tecnolog\u00eda \/ producci\u00f3n sin mano de obra\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica - Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica\" \/>\n\t\t<meta property=\"og:description\" content=\"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-27T23:58:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-28T13:49:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#blogposting\",\"name\":\"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"headline\":\"El Ataque Contra Los Inmigrantes y Todos Nosotros\\u00a0\",\"author\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rally-theleague.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Defend-imigrant-families-banner-8.15.25.jpg?fit=320%2C222&ssl=1\",\"width\":320,\"height\":222,\"caption\":\"Monrovia, CA, August 15, 2025 - March and vigil protesting the death of Carlos Roberto Montoya during an ICE raid at a local Home Depot the day before. \\nCredit: classsnrace\"},\"datePublished\":\"2025-08-27T19:58:32-04:00\",\"dateModified\":\"2025-08-28T09:49:14-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#webpage\"},\"articleSection\":\"Art\\u00edculo, Art\\u00edculo destacado - Espa\\u00f1ol, Capitalismo, El fascismo hoy, Elecciones \\\/ Gobernanza, Featured, Inmigraci\\u00f3n \\\/ Migraci\\u00f3n, Pobreza, Spotlight &#8211; English, Tecnolog\\u00eda \\\/ Producci\\u00f3n sin mano de obra, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"name\":\"Sistema de clase capitalista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"position\":2,\"name\":\"Sistema de clase capitalista\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/#listItem\",\"name\":\"Capitalismo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/#listItem\",\"position\":3,\"name\":\"Capitalismo\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#listItem\",\"name\":\"El Ataque Contra Los Inmigrantes y Todos Nosotros\\u00a0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"name\":\"Sistema de clase capitalista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#listItem\",\"position\":4,\"name\":\"El Ataque Contra Los Inmigrantes y Todos Nosotros\\u00a0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/capitalismo\\\/#listItem\",\"name\":\"Capitalismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\",\"name\":\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"description\":\"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\\u00f3n de cambio revolucionario\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"telephone\":\"+12699031659\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/\",\"name\":\"Brandon TekNoid\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d3e7f006a79d1f81216ec95f6a0372cdf5ee7c86ed3704f221f26ce0bd2673c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Brandon TekNoid\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#webpage\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/\",\"name\":\"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"description\":\"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\\u00fablicas est\\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\\u00fablicas est\\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rally-theleague.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Defend-imigrant-families-banner-8.15.25.jpg?fit=320%2C222&ssl=1\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#mainImage\",\"width\":320,\"height\":222,\"caption\":\"Monrovia, CA, August 15, 2025 - March and vigil protesting the death of Carlos Roberto Montoya during an ICE raid at a local Home Depot the day before. \\nCredit: classsnrace\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\\\/#mainImage\"},\"datePublished\":\"2025-08-27T19:58:32-04:00\",\"dateModified\":\"2025-08-28T09:49:14-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"name\":\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"alternateName\":\"Rally!\",\"description\":\"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\\u00f3n de cambio revolucionario\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica<\/title>\n\n","aioseo_head_json":{"title":"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.","canonical_url":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/","robots":"max-image-preview:large","keywords":"art\u00edculo,art\u00edculo destacado - espa\u00f1ol,capitalismo,el fascismo hoy,elecciones \/ gobernanza,featured,inmigraci\u00f3n \/ migraci\u00f3n,pobreza,spotlight &#8211; english,tecnolog\u00eda \/ producci\u00f3n sin mano de obra","webmasterTools":{"google-site-verification":"1XxvXmRwhGwQ0tsTTsKXy5R4fvTuv8OVEYVOEuqEAyA","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#blogposting","name":"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","headline":"El Ataque Contra Los Inmigrantes y Todos Nosotros\u00a0","author":{"@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author"},"publisher":{"@id":"https:\/\/rally-theleague.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/08\/Defend-imigrant-families-banner-8.15.25.jpg?fit=320%2C222&ssl=1","width":320,"height":222,"caption":"Monrovia, CA, August 15, 2025 - March and vigil protesting the death of Carlos Roberto Montoya during an ICE raid at a local Home Depot the day before. \nCredit: classsnrace"},"datePublished":"2025-08-27T19:58:32-04:00","dateModified":"2025-08-28T09:49:14-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#webpage"},"isPartOf":{"@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#webpage"},"articleSection":"Art\u00edculo, Art\u00edculo destacado - Espa\u00f1ol, Capitalismo, El fascismo hoy, Elecciones \/ Gobernanza, Featured, Inmigraci\u00f3n \/ Migraci\u00f3n, Pobreza, Spotlight &#8211; English, Tecnolog\u00eda \/ Producci\u00f3n sin mano de obra, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/rally-theleague.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","name":"Sistema de clase capitalista"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","position":2,"name":"Sistema de clase capitalista","item":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/#listItem","name":"Capitalismo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/#listItem","position":3,"name":"Capitalismo","item":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#listItem","name":"El Ataque Contra Los Inmigrantes y Todos Nosotros\u00a0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","name":"Sistema de clase capitalista"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#listItem","position":4,"name":"El Ataque Contra Los Inmigrantes y Todos Nosotros\u00a0","previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/#listItem","name":"Capitalismo"}}]},{"@type":"Organization","@id":"https:\/\/rally-theleague.org\/es\/#organization","name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","url":"https:\/\/rally-theleague.org\/es\/","telephone":"+12699031659"},{"@type":"Person","@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author","url":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/","name":"Brandon TekNoid","image":{"@type":"ImageObject","@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0d3e7f006a79d1f81216ec95f6a0372cdf5ee7c86ed3704f221f26ce0bd2673c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Brandon TekNoid"}},{"@type":"WebPage","@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#webpage","url":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/","name":"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/rally-theleague.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#breadcrumblist"},"author":{"@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author"},"creator":{"@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/08\/Defend-imigrant-families-banner-8.15.25.jpg?fit=320%2C222&ssl=1","@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#mainImage","width":320,"height":222,"caption":"Monrovia, CA, August 15, 2025 - March and vigil protesting the death of Carlos Roberto Montoya during an ICE raid at a local Home Depot the day before. \nCredit: classsnrace"},"primaryImageOfPage":{"@id":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/#mainImage"},"datePublished":"2025-08-27T19:58:32-04:00","dateModified":"2025-08-28T09:49:14-04:00"},{"@type":"WebSite","@id":"https:\/\/rally-theleague.org\/es\/#website","url":"https:\/\/rally-theleague.org\/es\/","name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","alternateName":"Rally!","description":"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","inLanguage":"es-ES","publisher":{"@id":"https:\/\/rally-theleague.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica - Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","og:type":"article","og:title":"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","og:description":"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.","og:url":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/","article:published_time":"2025-08-27T23:58:32+00:00","article:modified_time":"2025-08-28T13:49:14+00:00","twitter:card":"summary_large_image","twitter:title":"El Ataque Contra Los Inmigrantes y Todos Nosotros - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","twitter:description":"Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal. Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal."},"aioseo_meta_data":{"post_id":"8538","title":null,"description":"#post_excerpt Las redadas fascistas de ICE criminalizan a un sector de la clase trabajadora, volvi\u00e9ndonos unos contra otros en lugar de unirnos contra un gobierno controlado por multimillonarios. A medida que esto aumenta los gastos de subsistencia para todos, las protestas p\u00fablicas est\u00e1n obligando a los funcionarios estatales y locales a enfrentarse al gobierno federal.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-14 16:44:03","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-08-27 23:51:31","updated":"2026-05-14 16:44:03","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/\" title=\"Sistema de clase capitalista\">Sistema de clase capitalista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/\" title=\"Capitalismo\">Capitalismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Ataque Contra Los Inmigrantes y Todos Nosotros \n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/rally-theleague.org\/es\/"},{"label":"Sistema de clase capitalista","link":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/"},{"label":"Capitalismo","link":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/capitalismo\/"},{"label":"El Ataque Contra Los Inmigrantes y Todos Nosotros\u00a0","link":"https:\/\/rally-theleague.org\/es\/el-ataque-contra-los-inmigrantes-y-todos-nosotros\/"}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/08\/Defend-imigrant-families-banner-8.15.25.jpg?fit=320%2C222&ssl=1","_links":{"self":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/8538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/comments?post=8538"}],"version-history":[{"count":4,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/8538\/revisions"}],"predecessor-version":[{"id":8547,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/8538\/revisions\/8547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/media\/8523"}],"wp:attachment":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/media?parent=8538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/categories?post=8538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/tags?post=8538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}