{"id":8575,"date":"2025-09-17T19:18:22","date_gmt":"2025-09-17T23:18:22","guid":{"rendered":"https:\/\/rally-theleague.org\/?p=8575"},"modified":"2025-09-17T19:20:10","modified_gmt":"2025-09-17T23:20:10","slug":"la-lucha-contra-el-fascismo-en-oakland","status":"publish","type":"post","link":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/","title":{"rendered":"La Lucha Contra el Fascismo en Oakland"},"content":{"rendered":"<figure id=\"attachment_8561\" aria-describedby=\"caption-attachment-8561\" style=\"width: 480px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-8561\" src=\"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?resize=480%2C640&#038;ssl=1\" alt=\"\" width=\"480\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?w=480&amp;ssl=1 480w, https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?resize=300%2C400&amp;ssl=1 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><figcaption id=\"caption-attachment-8561\" class=\"wp-caption-text\">Los Angeles, June 14, 2025: Cartel levantado en la marcha No Reyes dice \u00ab<span class=\"s1\">Culpan a los inmigrantes para que no culpes a los multimillonarios<\/span>\u00bb<br \/>CREDIT: classnrace<\/figcaption><\/figure>\n<p class=\"p1\"><b>La Lucha Contra el Fascismo en Oakland <\/b><\/p>\n<p class=\"p3\"><b>Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC)<\/b><\/p>\n<p class=\"p4\">La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar las ganancias corporativas al desplazar a un n\u00famero cada vez mayor de residentes de bajos ingresos y de la clase trabajadora, y al eliminar la influencia pol\u00edtica de aquellos que todav\u00eda permanecen all\u00ed.<\/p>\n<p class=\"p3\">Este es un proceso bipartidista e incluye elementos que pertenecen abiertamente al movimiento MAGA, pero tambi\u00e9n a fascistas dentro del Partido Dem\u00f3crata. Esto empez\u00f3 con las destituciones en 2024 de la exalcaldesa y la fiscal progresista Pamela Price, acciones que contaron con el financiamiento de los multimillonarios. Los residentes de Oakland contraatacaron al elegir a una defensora de los derechos de los trabajadores, la alcaldesa Barbara Lee, en lugar del candidato respaldado por las corporaciones, Loren Taylor.<\/p>\n<p class=\"p3\">Posteriormente, en agosto, durante su conferencia de prensa en la que anunci\u00f3 la toma de Washington, D.C., el presidente Trump amenaz\u00f3 y atac\u00f3 abiertamente a Oakland.<span class=\"Apple-converted-space\">\u00a0 <\/span>Al respecto, la alcaldesa Lee respondi\u00f3 lo siguiente: \u201cNo vamos a permitir una ocupaci\u00f3n militar de la ciudad. Eso es lo que quiere hacer este presidente&#8230; \u00a1Esto forma parte de su esfuerzo por desmantelar la democracia!\u201d Trump ha establecido su manual estrat\u00e9gico con base en lo que sucede en el sur, donde las legislaturas de los estados republicanos han ido despojando paso a paso de la democracia a ciudades gobernadas por los dem\u00f3cratas, como Jackson, Misisipi; Nueva Orleans, Luisiana; Houston, Texas; y Atlanta, Georgia. Cada vez m\u00e1s, la clase gobernante recurre a la dictadura corporativa para controlar a una poblaci\u00f3n a la que el capitalismo no puede alimentar, brindarles viviendas, educar u ofrecerles atenci\u00f3n m\u00e9dica. Su objetivo es deshacerse de la \u201cmolestia\u201d de la democracia electoral y mantener a los movimientos de resistencia divididos y con miedo. La supremac\u00eda blanca es su arma favorita para dividir y conquistar.<\/p>\n<p class=\"p3\"><b>PRIMERO RESISTENCIA, LUEGO TRANSFORMACI\u00d3N <\/b><b><\/b><\/p>\n<p class=\"p3\">La pregunta en Oakland y en otras ciudades es la siguiente: \u00bfCu\u00e1l es el rumbo a seguir para la clase obrera, especialmente para los trabajadores negros, inmigrantes y otros despose\u00eddos? El pueblo no se ha mantenido pasivo. Desde 2022, el grupo para la organizaci\u00f3n vecinal de Oakland llamado <i>Care 4 Community Action<\/i> (Acci\u00f3n para Cuidar a la Comunidad \u2014C4C, por sus siglas en ingl\u00e9s) ha cuestionado la mentira de que los funcionarios negros electos no pueden controlar el crimen ni ofrecer servicios municipales. Adem\u00e1s, los trabajadores de Oakland se est\u00e1n organizando para lograr un verdadero cambio. Grupos de los campamentos de indigentes est\u00e1n creando alternativas visionarias: albergues autogestionados, cooperativas de vivienda arraigadas en la dignidad, no en la caridad, y fideicomisos de tierras comunitarias.<\/p>\n<p class=\"p4\">El condado de Alameda est\u00e1 ingresando a una nueva fase cr\u00edtica en la lucha contra la falta de viviendas. La reciente liberaci\u00f3n de m\u00e1s de <b>$1.800 millones<\/b> en fondos de la denominada Medida W para aplicar soluciones a la falta de vivienda representa una victoria significativa. Pero esta oportunidad va acompa\u00f1ada de un creciente peligro: una renovada ofensiva por parte de la clase gobernante para definir los t\u00e9rminos, limitar el alcance y, en \u00faltima instancia, despolitizar este movimiento por la justicia para la vivienda.<\/p>\n<p class=\"p3\">El condado de Alameda est\u00e1 enfrentando la misma lucha que en otras ciudades contra los trabajadores: el esfuerzo por mantener el poder en manos de personas que tienen dinero, en lugar de que est\u00e9 en manos de las personas que resultan directamente afectadas. Todav\u00eda est\u00e1 en juego la decisi\u00f3n de qui\u00e9nes ocupar\u00e1n un puesto en el comit\u00e9 de supervisi\u00f3n de la Medida W. \u00bfSer\u00e1n organizaciones de base como <a href=\"https:\/\/docs.google.com\/document\/d\/1Icojto3ds9UbGajirE7a6qT7nFywozDQ1H98X4FmUT4\/edit?usp=drivesdk\"><span class=\"s1\"><i>Black Solutions Lab<\/i> (Laboratorio de Soluciones Negras), <i>Care 4 Community<\/i> <i>Action<\/i> y <i>Wood Street Commons<\/i> (Comunas de la Calle Wood)<\/span><\/a>, que desean aplicar modelos impulsados por las comunidades, o ser\u00e1n los bur\u00f3cratas de carrera y las organizaciones sin fines de lucro que est\u00e1n desconectadas de la realidad y tienen m\u00e1s inter\u00e9s en mantener su financiamiento que en resolver la crisis? Esto no se trata solo de ofrecer mejores servicios, sino tambi\u00e9n de construir poder para el pueblo y transformar los sistemas existentes. Los trabajadores est\u00e1n luchando por lograr la aplicaci\u00f3n inmediata de la Medida W, lo que incluye lo siguiente:<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\">Reformas en todo el sistema, para ir m\u00e1s all\u00e1 de las soluciones a nivel de los servicios para avanzar hacia cambios estructurales.<\/li>\n<li class=\"li3\">Una lista p\u00fablica de edificios vac\u00edos o subutilizados, a fin de identificar espacios que puedan albergar a personas desplazadas en las mismas \u00e1reas donde se encuentran los campamentos, para as\u00ed lograr que nuestros vecinos sin viviendas se queden dentro de la comunidad.<\/li>\n<li class=\"li3\">Apoyar los fideicomisos de tierras comunitarias, las cooperativas y los modelos de capital social basados en el trabajo invertido (<i>sweat equity<\/i>), para as\u00ed empoderar a los residentes y resistirse a la mercantilizaci\u00f3n.<\/li>\n<li class=\"li3\">Suspender temporalmente la aplicaci\u00f3n de sanciones contra las personas que viven en veh\u00edculos y ofrecer zonas seguras designadas para estacionarse y vivir.<\/li>\n<\/ul>\n<p class=\"p3\">En el condado de Alameda, las familias de cuatro personas con ingresos extremadamente bajos ganan menos de $46.700 al a\u00f1o. El alquiler promedio para una familia de cuatro es de $2.761. Una familia tendr\u00eda que ganar $110.480 al a\u00f1o para pagar un alquiler equivalente al 30 por ciento de sus ingresos. Aunque el salario m\u00ednimo es de $17,46, los trabajadores de tiempo completo tendr\u00edan que ganar $53,12 por hora para poder pagar ese alquiler promedio. Esto representa una carga extremadamente pesada que genera dificultades para las <b>familias trabajadoras<\/b>.<\/p>\n<p class=\"p3\">Como en todas partes, la crisis de vivienda en el condado de Alameda se trata de sistemas que no responden a las necesidades de las familias trabajadoras, as\u00ed como de delitos corporativos \u201clegales\u201d que destruyen nuestra comunidad, como conspirar para aumentar los precios de las viviendas y llevar a cabo campa\u00f1as organizadas de desalojo. Al igual que en la campa\u00f1a de Mamdani en Nueva York, la asequibilidad de las viviendas es el tema que est\u00e1 movilizando a los trabajadores.<\/p>\n<p class=\"p3\"><b>LA UNIDAD DE LA CLASE<\/b><b><\/b><\/p>\n<p class=\"p3\">Estamos librando una lucha de valores y visiones. Por un lado, se encuentra el enfoque de gesti\u00f3n corporativa, que considera que las personas sin viviendas son problemas que se deben controlar o gestionar y que los fondos p\u00fablicos se invierten mejor en personas \u201cm\u00e1s merecedoras\u201d. Por otra parte, existe una visi\u00f3n transformadora que considera que la vivienda es un derecho humano y que las personas sin viviendas son l\u00edderes en el dise\u00f1o de su propio futuro. Las ideas de la clase gobernante ya se est\u00e1n filtrando en los debates p\u00fablicos (tales como limitar el financiamiento de albergues a aquellas instalaciones que cumplan con criterios estrictos sobre el n\u00famero de camas, o aumentar los pagos por cama sin cuestionar la propia estructura de la prestaci\u00f3n de servicios). Estos marcos despolitizan la crisis y obstaculizan respuestas innovadoras dirigidas por la comunidad.<\/p>\n<p class=\"p3\">Pero tambi\u00e9n est\u00e1n surgiendo ideas que sirven para lograr la unidad pol\u00edtica que ser\u00e1 necesaria para vencer el fascismo. Los grupos que apoyan diferentes aspectos de las agendas de la clase trabajadora est\u00e1n d\u00e1ndose cuenta de que tienen que salir de su aislamiento. La unidad y el apoyo mutuo fomentan todos nuestros temas interrelacionados: la lucha por las necesidades b\u00e1sicas, la lucha para recuperar tierras p\u00fablicas para el bien p\u00fablico, el llamado a la reforma de las pol\u00edticas sobre albergues, tanto en el \u00e1mbito municipal como a nivel del condado, y la petici\u00f3n de contar con un departamento de reclamaciones y cumplimiento que trabaje para las personas, no solo para la burocracia. La Alianza de Californianos para el Empoderamiento Comunitario (ACCE, por sus siglas en ingl\u00e9s) est\u00e1 sirviendo de ejemplo al combinar las necesidades de los derechos de los inquilinos con los derechos migratorios. Las manifestaciones llamadas <i>Indivisible Hands Off<\/i> (Indivisible: Manos Fuera) y <i>No Kings<\/i> (No hay Reyes) est\u00e1n ayudando a defender la democracia. \u00a1Ese tipo de entendimiento \u2014de que est\u00e1n luchando contra todos nosotros y de que debemos unirnos\u2014 nos llevar\u00e1 hacia la victoria!<\/p>\n<p><b>Publicado el Septiembre 17 <\/b><b>de 2025<\/b><br \/>\nEste art\u00edculo se origin\u00f3 en \u00a1Agrup\u00e9monos!<br \/>\nCORREOS. Box 408002 Chicago, IL 60640<br \/>\n<a href=\"mailto:rally@lrna.org\" target=\"_blank\" rel=\"noopener\">rally@lrna.org<\/a><br \/>\nLibre de reproducir a menos que se indique lo contrario. Incluya este mensaje con cualquier reproducci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":8561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[196,201,218,217,259,227,210],"tags":[],"class_list":["post-8575","post","type-post","status-publish","format-standard","has-post-thumbnail","category-articulo","category-clases","category-el-fascismo-hoy","category-elecciones-gobernanza","category-featured-es","category-pobreza_race-class_gender","category-vivienda-personas-sin-hogar"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Brandon TekNoid\"\/>\n\t<meta name=\"google-site-verification\" content=\"1XxvXmRwhGwQ0tsTTsKXy5R4fvTuv8OVEYVOEuqEAyA\" \/>\n\t<meta name=\"keywords\" content=\"art\u00edculo,clases,el fascismo hoy,elecciones \/ gobernanza,featured,pobreza,vivienda \/ personas sin hogar\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica - Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica\" \/>\n\t\t<meta property=\"og:description\" content=\"La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-17T23:18:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-17T23:20:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#blogposting\",\"name\":\"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"headline\":\"La Lucha Contra el Fascismo en Oakland\",\"author\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rally-theleague.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/They-blame-immigrants-not-billionaires-rotated.jpg?fit=480%2C640&ssl=1\",\"width\":480,\"height\":640,\"caption\":\"Los Angeles, June 14, 2025: No Kings Day marcher sees clearly that the attack on migrants must be fought with class unity.\\nCREDIT: classnrace\"},\"datePublished\":\"2025-09-17T19:18:22-04:00\",\"dateModified\":\"2025-09-17T19:20:10-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#webpage\"},\"articleSection\":\"Art\\u00edculo, Clases, El fascismo hoy, Elecciones \\\/ Gobernanza, Featured, Pobreza, Vivienda \\\/ Personas sin hogar, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"name\":\"Sistema de clase capitalista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"position\":2,\"name\":\"Sistema de clase capitalista\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/clases\\\/#listItem\",\"name\":\"Clases\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/clases\\\/#listItem\",\"position\":3,\"name\":\"Clases\",\"item\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/clases\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#listItem\",\"name\":\"La Lucha Contra el Fascismo en Oakland\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/#listItem\",\"name\":\"Sistema de clase capitalista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#listItem\",\"position\":4,\"name\":\"La Lucha Contra el Fascismo en Oakland\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/category\\\/sistema-de-clase-capitalista\\\/clases\\\/#listItem\",\"name\":\"Clases\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\",\"name\":\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"description\":\"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\\u00f3n de cambio revolucionario\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"telephone\":\"+12699031659\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/\",\"name\":\"Brandon TekNoid\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d3e7f006a79d1f81216ec95f6a0372cdf5ee7c86ed3704f221f26ce0bd2673c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Brandon TekNoid\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#webpage\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/\",\"name\":\"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"description\":\"La Lucha Contra el Fascismo en Oakland Por el Comit\\u00e9 Electoral sobre las Necesidades B\\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\\u00e1 librando contra los residentes de Oakland, California, est\\u00e1 sirviendo como un caso que ilustra la consolidaci\\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/author\\\/brandon-teknoid\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rally-theleague.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/They-blame-immigrants-not-billionaires-rotated.jpg?fit=480%2C640&ssl=1\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#mainImage\",\"width\":480,\"height\":640,\"caption\":\"Los Angeles, June 14, 2025: No Kings Day marcher sees clearly that the attack on migrants must be fought with class unity.\\nCREDIT: classnrace\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/la-lucha-contra-el-fascismo-en-oakland\\\/#mainImage\"},\"datePublished\":\"2025-09-17T19:18:22-04:00\",\"dateModified\":\"2025-09-17T19:20:10-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/\",\"name\":\"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\\u00e9rica\",\"alternateName\":\"Rally!\",\"description\":\"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\\u00f3n de cambio revolucionario\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/rally-theleague.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica<\/title>\n\n","aioseo_head_json":{"title":"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar","canonical_url":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/","robots":"max-image-preview:large","keywords":"art\u00edculo,clases,el fascismo hoy,elecciones \/ gobernanza,featured,pobreza,vivienda \/ personas sin hogar","webmasterTools":{"google-site-verification":"1XxvXmRwhGwQ0tsTTsKXy5R4fvTuv8OVEYVOEuqEAyA","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#blogposting","name":"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","headline":"La Lucha Contra el Fascismo en Oakland","author":{"@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author"},"publisher":{"@id":"https:\/\/rally-theleague.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?fit=480%2C640&ssl=1","width":480,"height":640,"caption":"Los Angeles, June 14, 2025: No Kings Day marcher sees clearly that the attack on migrants must be fought with class unity.\nCREDIT: classnrace"},"datePublished":"2025-09-17T19:18:22-04:00","dateModified":"2025-09-17T19:20:10-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#webpage"},"isPartOf":{"@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#webpage"},"articleSection":"Art\u00edculo, Clases, El fascismo hoy, Elecciones \/ Gobernanza, Featured, Pobreza, Vivienda \/ Personas sin hogar, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/rally-theleague.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","name":"Sistema de clase capitalista"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","position":2,"name":"Sistema de clase capitalista","item":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/clases\/#listItem","name":"Clases"},"previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/clases\/#listItem","position":3,"name":"Clases","item":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/clases\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#listItem","name":"La Lucha Contra el Fascismo en Oakland"},"previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/#listItem","name":"Sistema de clase capitalista"}},{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#listItem","position":4,"name":"La Lucha Contra el Fascismo en Oakland","previousItem":{"@type":"ListItem","@id":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/clases\/#listItem","name":"Clases"}}]},{"@type":"Organization","@id":"https:\/\/rally-theleague.org\/es\/#organization","name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","url":"https:\/\/rally-theleague.org\/es\/","telephone":"+12699031659"},{"@type":"Person","@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author","url":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/","name":"Brandon TekNoid","image":{"@type":"ImageObject","@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0d3e7f006a79d1f81216ec95f6a0372cdf5ee7c86ed3704f221f26ce0bd2673c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Brandon TekNoid"}},{"@type":"WebPage","@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#webpage","url":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/","name":"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","description":"La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/rally-theleague.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#breadcrumblist"},"author":{"@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author"},"creator":{"@id":"https:\/\/rally-theleague.org\/es\/author\/brandon-teknoid\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?fit=480%2C640&ssl=1","@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#mainImage","width":480,"height":640,"caption":"Los Angeles, June 14, 2025: No Kings Day marcher sees clearly that the attack on migrants must be fought with class unity.\nCREDIT: classnrace"},"primaryImageOfPage":{"@id":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/#mainImage"},"datePublished":"2025-09-17T19:18:22-04:00","dateModified":"2025-09-17T19:20:10-04:00"},{"@type":"WebSite","@id":"https:\/\/rally-theleague.org\/es\/#website","url":"https:\/\/rally-theleague.org\/es\/","name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","alternateName":"Rally!","description":"Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","inLanguage":"es-ES","publisher":{"@id":"https:\/\/rally-theleague.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica - Uniendo las luchas por las necesidades humanas y por el planeta con una visi\u00f3n de cambio revolucionario","og:type":"article","og:title":"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","og:description":"La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar","og:url":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/","article:published_time":"2025-09-17T23:18:22+00:00","article:modified_time":"2025-09-17T23:20:10+00:00","twitter:card":"summary_large_image","twitter:title":"La Lucha Contra el Fascismo en Oakland - Agrupemonos - Voz de la Liga de Revolucionarios por una Nueva Am\u00e9rica","twitter:description":"La Lucha Contra el Fascismo en Oakland Por el Comit\u00e9 Electoral sobre las Necesidades B\u00e1sicas de Oakland (OBNEC) La guerra actual que se est\u00e1 librando contra los residentes de Oakland, California, est\u00e1 sirviendo como un caso que ilustra la consolidaci\u00f3n del poder fascista en diversas ciudades de todos los Estados Unidos. Su objetivo es aumentar"},"aioseo_meta_data":{"post_id":"8575","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-14 16:45:36","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-17 23:12:46","updated":"2026-05-14 16:45:36","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/\" title=\"Sistema de clase capitalista\">Sistema de clase capitalista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/clases\/\" title=\"Clases\">Clases<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa Lucha Contra el Fascismo en Oakland\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/rally-theleague.org\/es\/"},{"label":"Sistema de clase capitalista","link":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/"},{"label":"Clases","link":"https:\/\/rally-theleague.org\/es\/category\/sistema-de-clase-capitalista\/clases\/"},{"label":"La Lucha Contra el Fascismo en Oakland","link":"https:\/\/rally-theleague.org\/es\/la-lucha-contra-el-fascismo-en-oakland\/"}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rally-theleague.org\/wp-content\/uploads\/2025\/09\/They-blame-immigrants-not-billionaires-rotated.jpg?fit=480%2C640&ssl=1","_links":{"self":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/8575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/comments?post=8575"}],"version-history":[{"count":1,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/8575\/revisions"}],"predecessor-version":[{"id":8576,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/posts\/8575\/revisions\/8576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/media\/8561"}],"wp:attachment":[{"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/media?parent=8575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/categories?post=8575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rally-theleague.org\/es\/wp-json\/wp\/v2\/tags?post=8575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}